{"id":4514,"date":"2026-03-26T16:31:23","date_gmt":"2026-03-26T19:31:23","guid":{"rendered":"https:\/\/mdcenergia.com.br\/?p=4514"},"modified":"2026-03-26T16:31:23","modified_gmt":"2026-03-26T19:31:23","slug":"mdc-e-pioneira-na-producao-de-biometano-em-escala-comercial","status":"publish","type":"post","link":"https:\/\/mdcenergia.com.br\/en\/mdc-e-pioneira-na-producao-de-biometano-em-escala-comercial\/","title":{"rendered":"Conhe\u00e7a os bastidores de uma usina de produ\u00e7\u00e3o de biometano"},"content":{"rendered":"<p>Produzido a partir do reaproveitamento de res\u00edduos org\u00e2nicos, o biometano \u00e9 um exemplo pr\u00e1tico de economia circular e protagonista na estrat\u00e9gia de descarboniza\u00e7\u00e3o do Brasil. Esse papel de destaque n\u00e3o \u00e9 surpresa \u2013 principalmente para a MDC, que foi a primeira empresa do pa\u00eds a produzir o biocombust\u00edvel em escala comercial e a injet\u00e1-lo diretamente na rede de distribui\u00e7\u00e3o.<\/p>\n<p>Cada vez mais, o mercado vem reconhecendo o biometano como um dos caminhos mais r\u00e1pidos e economicamente vi\u00e1veis para a transi\u00e7\u00e3o energ\u00e9tica. Diferente de outras rotas de descarboniza\u00e7\u00e3o, o biometano j\u00e1 tem uma maturidade quando comparado a tecnologias ainda em desenvolvimento. Compat\u00edvel com gasodutos, redes locais, ind\u00fastrias e ve\u00edculos, incluindo frotas pesadas, o biocombust\u00edvel pode aproveitar uma infraestrutura que j\u00e1 existe no pa\u00eds. Isso representa uma solu\u00e7\u00e3o mais r\u00e1pida e com menor custo para empresas e governos imbu\u00eddos na redu\u00e7\u00e3o das suas emiss\u00f5es.<\/p>\n<p>Convidamos voc\u00ea a conhecer mais sobre a experi\u00eancia da MDC nesse mercado complexo no material que compartilhamos abaixo! Gravado na Biometano Caieiras, planta que temos em S\u00e3o Paulo em parceria com a Solv\u00ed Essencis Ambiental, o v\u00eddeo integra a s\u00e9rie Bioenergy Horizons. Coproduzido pela World Bioenergy Association e pela BlackRook Media, o document\u00e1rio aborda o desenvolvimento do mercado global de energia renov\u00e1vel.<\/p>\n<p>Com participa\u00e7\u00e3o de Manuela Kayath, Presidente do Conselho de Administra\u00e7\u00e3o da MDC, e Thales Motta, Diretor de Opera\u00e7\u00f5es, o epis\u00f3dio mostra na pr\u00e1tica o processo de produ\u00e7\u00e3o do biometano a partir do reaproveitamento de res\u00edduos org\u00e2nicos, transformando um passivo ambiental que retorna \u00e0 sociedade como combust\u00edvel.<\/p>\n<p>Confira o v\u00eddeo completo abaixo:<\/p>\n<p><iframe title=\"YouTube video player\" src=\"https:\/\/www.youtube.com\/embed\/JQOAMuEzIyY?si=JPKgvKOR6UV9SFjq\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>","protected":false},"excerpt":{"rendered":"<p>Produzido a partir do reaproveitamento de res\u00edduos org\u00e2nicos, o biometano \u00e9 um exemplo pr\u00e1tico de economia circular e protagonista na estrat\u00e9gia de descarboniza\u00e7\u00e3o do Brasil. Esse papel de destaque n\u00e3o \u00e9 surpresa \u2013 principalmente para a MDC, que foi a primeira empresa do pa\u00eds a produzir o biocombust\u00edvel em escala comercial e a injet\u00e1-lo diretamente [&hellip;]<\/p>\n","protected":false},"author":17,"featured_media":4515,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[48,51,225],"class_list":["post-4514","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","tag-biometano","tag-gas","tag-gas-renovavel"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Conhe\u00e7a os bastidores de uma usina de produ\u00e7\u00e3o de biometano - MDC - Energia - Holding<\/title>\n<meta name=\"description\" content=\"O biometano \u00e9 um dos principais combust\u00edveis de transi\u00e7\u00e3o para a economia de baixo carbono. Entenda como a MDC Energia se destaca no setor!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mdcenergia.com.br\/en\/mdc-e-pioneira-na-producao-de-biometano-em-escala-comercial\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Conhe\u00e7a os bastidores de uma usina de produ\u00e7\u00e3o de biometano - MDC - Energia - Holding\" \/>\n<meta property=\"og:description\" content=\"O biometano \u00e9 um dos principais combust\u00edveis de transi\u00e7\u00e3o para a economia de baixo carbono. Entenda como a MDC Energia se destaca no setor!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mdcenergia.com.br\/en\/mdc-e-pioneira-na-producao-de-biometano-em-escala-comercial\/\" \/>\n<meta property=\"og:site_name\" content=\"MDC - Energia - Holding\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-26T19:31:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mdcenergia.com.br\/wp-content\/uploads\/2026\/03\/Biometano-Caieiras-scaled.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mdcenergia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"mdcenergia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/mdcenergia.com.br\\\/mdc-e-pioneira-na-producao-de-biometano-em-escala-comercial\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mdcenergia.com.br\\\/mdc-e-pioneira-na-producao-de-biometano-em-escala-comercial\\\/\"},\"author\":{\"name\":\"mdcenergia\",\"@id\":\"https:\\\/\\\/mdcenergia.com.br\\\/#\\\/schema\\\/person\\\/4de5e8e07f80ec1846bd74631222b03d\"},\"headline\":\"Conhe\u00e7a os bastidores de uma usina de produ\u00e7\u00e3o de biometano\",\"datePublished\":\"2026-03-26T19:31:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/mdcenergia.com.br\\\/mdc-e-pioneira-na-producao-de-biometano-em-escala-comercial\\\/\"},\"wordCount\":304,\"publisher\":{\"@id\":\"https:\\\/\\\/mdcenergia.com.br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/mdcenergia.com.br\\\/mdc-e-pioneira-na-producao-de-biometano-em-escala-comercial\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mdcenergia.com.br\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Biometano-Caieiras-scaled.jpeg\",\"keywords\":[\"Biometano\",\"G\u00e1s\",\"G\u00e1s Renov\u00e1vel\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mdcenergia.com.br\\\/mdc-e-pioneira-na-producao-de-biometano-em-escala-comercial\\\/\",\"url\":\"https:\\\/\\\/mdcenergia.com.br\\\/mdc-e-pioneira-na-producao-de-biometano-em-escala-comercial\\\/\",\"name\":\"Conhe\u00e7a os bastidores de uma usina de produ\u00e7\u00e3o de biometano - MDC - Energia - Holding\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mdcenergia.com.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mdcenergia.com.br\\\/mdc-e-pioneira-na-producao-de-biometano-em-escala-comercial\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mdcenergia.com.br\\\/mdc-e-pioneira-na-producao-de-biometano-em-escala-comercial\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mdcenergia.com.br\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Biometano-Caieiras-scaled.jpeg\",\"datePublished\":\"2026-03-26T19:31:23+00:00\",\"description\":\"O biometano \u00e9 um dos principais combust\u00edveis de transi\u00e7\u00e3o para a economia de baixo carbono. Entenda como a MDC Energia se destaca no setor!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mdcenergia.com.br\\\/mdc-e-pioneira-na-producao-de-biometano-em-escala-comercial\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mdcenergia.com.br\\\/mdc-e-pioneira-na-producao-de-biometano-em-escala-comercial\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/mdcenergia.com.br\\\/mdc-e-pioneira-na-producao-de-biometano-em-escala-comercial\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mdcenergia.com.br\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Biometano-Caieiras-scaled.jpeg\",\"contentUrl\":\"https:\\\/\\\/mdcenergia.com.br\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Biometano-Caieiras-scaled.jpeg\",\"width\":2560,\"height\":1920},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mdcenergia.com.br\\\/mdc-e-pioneira-na-producao-de-biometano-em-escala-comercial\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/mdcenergia.com.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Conhe\u00e7a os bastidores de uma usina de produ\u00e7\u00e3o de biometano\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mdcenergia.com.br\\\/#website\",\"url\":\"https:\\\/\\\/mdcenergia.com.br\\\/\",\"name\":\"MDC - Energia - Holding\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/mdcenergia.com.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mdcenergia.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mdcenergia.com.br\\\/#organization\",\"name\":\"MDC - Energia - Holding\",\"url\":\"https:\\\/\\\/mdcenergia.com.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/mdcenergia.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mdcenergia.com.br\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/MDC_RGB_Horizontal_Tagline_Negativo.png\",\"contentUrl\":\"https:\\\/\\\/mdcenergia.com.br\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/MDC_RGB_Horizontal_Tagline_Negativo.png\",\"width\":2194,\"height\":1212,\"caption\":\"MDC - Energia - Holding\"},\"image\":{\"@id\":\"https:\\\/\\\/mdcenergia.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/mdcenergia.com.br\\\/#\\\/schema\\\/person\\\/4de5e8e07f80ec1846bd74631222b03d\",\"name\":\"mdcenergia\",\"url\":\"https:\\\/\\\/mdcenergia.com.br\\\/en\\\/author\\\/mdcenergia\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Conhe\u00e7a os bastidores de uma usina de produ\u00e7\u00e3o de biometano - MDC - Energia - Holding","description":"O biometano \u00e9 um dos principais combust\u00edveis de transi\u00e7\u00e3o para a economia de baixo carbono. Entenda como a MDC Energia se destaca no setor!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mdcenergia.com.br\/en\/mdc-e-pioneira-na-producao-de-biometano-em-escala-comercial\/","og_locale":"en_US","og_type":"article","og_title":"Conhe\u00e7a os bastidores de uma usina de produ\u00e7\u00e3o de biometano - MDC - Energia - Holding","og_description":"O biometano \u00e9 um dos principais combust\u00edveis de transi\u00e7\u00e3o para a economia de baixo carbono. Entenda como a MDC Energia se destaca no setor!","og_url":"https:\/\/mdcenergia.com.br\/en\/mdc-e-pioneira-na-producao-de-biometano-em-escala-comercial\/","og_site_name":"MDC - Energia - Holding","article_published_time":"2026-03-26T19:31:23+00:00","og_image":[{"width":2560,"height":1920,"url":"https:\/\/mdcenergia.com.br\/wp-content\/uploads\/2026\/03\/Biometano-Caieiras-scaled.jpeg","type":"image\/jpeg"}],"author":"mdcenergia","twitter_card":"summary_large_image","twitter_misc":{"Written by":"mdcenergia","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mdcenergia.com.br\/mdc-e-pioneira-na-producao-de-biometano-em-escala-comercial\/#article","isPartOf":{"@id":"https:\/\/mdcenergia.com.br\/mdc-e-pioneira-na-producao-de-biometano-em-escala-comercial\/"},"author":{"name":"mdcenergia","@id":"https:\/\/mdcenergia.com.br\/#\/schema\/person\/4de5e8e07f80ec1846bd74631222b03d"},"headline":"Conhe\u00e7a os bastidores de uma usina de produ\u00e7\u00e3o de biometano","datePublished":"2026-03-26T19:31:23+00:00","mainEntityOfPage":{"@id":"https:\/\/mdcenergia.com.br\/mdc-e-pioneira-na-producao-de-biometano-em-escala-comercial\/"},"wordCount":304,"publisher":{"@id":"https:\/\/mdcenergia.com.br\/#organization"},"image":{"@id":"https:\/\/mdcenergia.com.br\/mdc-e-pioneira-na-producao-de-biometano-em-escala-comercial\/#primaryimage"},"thumbnailUrl":"https:\/\/mdcenergia.com.br\/wp-content\/uploads\/2026\/03\/Biometano-Caieiras-scaled.jpeg","keywords":["Biometano","G\u00e1s","G\u00e1s Renov\u00e1vel"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/mdcenergia.com.br\/mdc-e-pioneira-na-producao-de-biometano-em-escala-comercial\/","url":"https:\/\/mdcenergia.com.br\/mdc-e-pioneira-na-producao-de-biometano-em-escala-comercial\/","name":"Conhe\u00e7a os bastidores de uma usina de produ\u00e7\u00e3o de biometano - MDC - Energia - Holding","isPartOf":{"@id":"https:\/\/mdcenergia.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mdcenergia.com.br\/mdc-e-pioneira-na-producao-de-biometano-em-escala-comercial\/#primaryimage"},"image":{"@id":"https:\/\/mdcenergia.com.br\/mdc-e-pioneira-na-producao-de-biometano-em-escala-comercial\/#primaryimage"},"thumbnailUrl":"https:\/\/mdcenergia.com.br\/wp-content\/uploads\/2026\/03\/Biometano-Caieiras-scaled.jpeg","datePublished":"2026-03-26T19:31:23+00:00","description":"O biometano \u00e9 um dos principais combust\u00edveis de transi\u00e7\u00e3o para a economia de baixo carbono. Entenda como a MDC Energia se destaca no setor!","breadcrumb":{"@id":"https:\/\/mdcenergia.com.br\/mdc-e-pioneira-na-producao-de-biometano-em-escala-comercial\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mdcenergia.com.br\/mdc-e-pioneira-na-producao-de-biometano-em-escala-comercial\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/mdcenergia.com.br\/mdc-e-pioneira-na-producao-de-biometano-em-escala-comercial\/#primaryimage","url":"https:\/\/mdcenergia.com.br\/wp-content\/uploads\/2026\/03\/Biometano-Caieiras-scaled.jpeg","contentUrl":"https:\/\/mdcenergia.com.br\/wp-content\/uploads\/2026\/03\/Biometano-Caieiras-scaled.jpeg","width":2560,"height":1920},{"@type":"BreadcrumbList","@id":"https:\/\/mdcenergia.com.br\/mdc-e-pioneira-na-producao-de-biometano-em-escala-comercial\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/mdcenergia.com.br\/"},{"@type":"ListItem","position":2,"name":"Conhe\u00e7a os bastidores de uma usina de produ\u00e7\u00e3o de biometano"}]},{"@type":"WebSite","@id":"https:\/\/mdcenergia.com.br\/#website","url":"https:\/\/mdcenergia.com.br\/","name":"MDC - Energia - Holding","description":"","publisher":{"@id":"https:\/\/mdcenergia.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mdcenergia.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/mdcenergia.com.br\/#organization","name":"MDC - Energia - Holding","url":"https:\/\/mdcenergia.com.br\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/mdcenergia.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/mdcenergia.com.br\/wp-content\/uploads\/2020\/02\/MDC_RGB_Horizontal_Tagline_Negativo.png","contentUrl":"https:\/\/mdcenergia.com.br\/wp-content\/uploads\/2020\/02\/MDC_RGB_Horizontal_Tagline_Negativo.png","width":2194,"height":1212,"caption":"MDC - Energia - Holding"},"image":{"@id":"https:\/\/mdcenergia.com.br\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/mdcenergia.com.br\/#\/schema\/person\/4de5e8e07f80ec1846bd74631222b03d","name":"mdcenergia","url":"https:\/\/mdcenergia.com.br\/en\/author\/mdcenergia\/"}]}},"_links":{"self":[{"href":"https:\/\/mdcenergia.com.br\/en\/wp-json\/wp\/v2\/posts\/4514","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mdcenergia.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mdcenergia.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mdcenergia.com.br\/en\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/mdcenergia.com.br\/en\/wp-json\/wp\/v2\/comments?post=4514"}],"version-history":[{"count":1,"href":"https:\/\/mdcenergia.com.br\/en\/wp-json\/wp\/v2\/posts\/4514\/revisions"}],"predecessor-version":[{"id":4516,"href":"https:\/\/mdcenergia.com.br\/en\/wp-json\/wp\/v2\/posts\/4514\/revisions\/4516"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mdcenergia.com.br\/en\/wp-json\/wp\/v2\/media\/4515"}],"wp:attachment":[{"href":"https:\/\/mdcenergia.com.br\/en\/wp-json\/wp\/v2\/media?parent=4514"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mdcenergia.com.br\/en\/wp-json\/wp\/v2\/categories?post=4514"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mdcenergia.com.br\/en\/wp-json\/wp\/v2\/tags?post=4514"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}